{"id":6241,"date":"2021-06-09T22:34:07","date_gmt":"2021-06-09T14:34:07","guid":{"rendered":"https:\/\/op2.comtnet.com\/?page_id=6241"},"modified":"2021-11-02T14:57:08","modified_gmt":"2021-11-02T06:57:08","slug":"%e8%81%af%e7%b5%a1%e6%88%91%e5%80%91","status":"publish","type":"page","link":"https:\/\/colareb-asia.com\/en\/%e8%81%af%e7%b5%a1%e6%88%91%e5%80%91\/","title":{"rendered":"Contact Us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6241\" class=\"elementor elementor-6241\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-857201c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"857201c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-340b8b2\" data-id=\"340b8b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4646003a elementor-widget elementor-widget-heading\" data-id=\"4646003a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u806f\u7d61\u6211\u5011<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc5b7a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc5b7a9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-33e7b5c\" data-id=\"33e7b5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d208f2 elementor-widget elementor-widget-heading\" data-id=\"5d208f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">ColaReb \u5927\u4e2d\u83ef\u5340\u7e3d\u4ee3\u7406\u5546<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2baa0ed7 elementor-widget elementor-widget-text-editor\" data-id=\"2baa0ed7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u6137\u7fd4\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8<\/p><p>\u5730\u5740\uff1a\u53f0\u5317\u5e02\u677e\u5c71\u5340\u5357\u4eac\u6771\u8def\u4e94\u6bb5188\u865f3\u6a13\u4e4b2<\/p><p>TEL\uff1a+886 2 7702-1272<\/p><p>EMAIL\uff1ainfo@colareb-asia.com<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-11cd4af\" data-id=\"11cd4af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec1e461 elementor-widget elementor-widget-heading\" data-id=\"ec1e461\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u767c\u9001\u8a0a\u606f<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52a4c35 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"52a4c35\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;\\u4e0b\\u4e00\\u7bc7&quot;,&quot;step_previous_label&quot;:&quot;\\u4e0a\\u4e00\\u7bc7&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"\u65b0\u8868\u55ae\" aria-label=\"\u65b0\u8868\u55ae\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"6241\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"52a4c35\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\u806f\u7d61\u6211\u5011\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"6241\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u60a8\u7684\u5927\u540d (\u5fc5\u586b)\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u96fb\u5b50\u90f5\u4ef6\u5730\u5740 (\u5fc5\u586b)\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_35eb1c7 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_35eb1c7\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u4e3b\u65e8 (\u5fc5\u586b)\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_35eb1c7]\" id=\"form-field-field_35eb1c7\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u554f\u984c\u6216\u5efa\u8b70 (\u5fc5\u586b)\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u9001\u51fa<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-acd0721 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"acd0721\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-248cf961\" data-id=\"248cf961\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0012398 elementor-widget elementor-widget-text-editor\" data-id=\"0012398\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"lead\" style=\"text-align: center;\"><span style=\"color: #000000;\">\u806f\u7d61\u6211\u5011\u4e4b\u524d\u8acb\u5148\u53c3\u8003<\/span><a href=\"http:\/\/colareb-asia.com\/%e5%b8%b8%e8%a6%8b%e5%95%8f%e9%a1%8c%e8%88%87%e8%b3%bc%e7%89%a9%e9%a0%88%e7%9f%a5\/\"><span style=\"color: #ff0000;\"><strong>\u8a02\u8cfc\u9808\u77e5<\/strong><\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37e444aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37e444aa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b98d27e\" data-id=\"3b98d27e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d8a99f elementor-widget elementor-widget-elementskit-accordion\" data-id=\"2d8a99f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a579213a1855\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-2d8a99f\">\n                        <a href=\"#collapse-057db3b6a579213a1855\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-057db3b6a579213a1855\" aria-expanded=\"false\" aria-controls=\"Collapse-057db3b6a579213a1855\">\n                            \n                            <span class=\"ekit-accordion-title\">\u60a8\u8207ColaReb.it\u7684\u95dc\u4fc2 ?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-057db3b6a579213a1855\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-2d8a99f\" data-parent=\"#accordion-6a579213a1855\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"accordion-item\"><div class=\"accordion-inner\"><p>\u6211\u5011\u662fColaReb\u00ae \u5728\u5927\u4e2d\u83ef\u5340 (\u4e2d\u570b\u3001\u9999\u6e2f\u3001\u6fb3\u9580\u3001\u53f0\u7063) \u7684\u7e3d\u4ee3\u7406\u5546\u3002<\/p><\/div><\/div><div class=\"accordion-item\">\u00a0<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-2d8a99f\">\n                        <a href=\"#collapse-f3b430f6a579213a1855\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-f3b430f6a579213a1855\" aria-expanded=\"false\" aria-controls=\"Collapse-f3b430f6a579213a1855\">\n                            \n                            <span class=\"ekit-accordion-title\">\u5546\u54c1\u662f\u5426\u70ba\u7fa9\u5927\u5229\u6b63\u54c1 ?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-f3b430f6a579213a1855\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-2d8a99f\" data-parent=\"#accordion-6a579213a1855\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"accordion-item\"><div class=\"accordion-inner\"><div class=\"accordion-item\"><div class=\"accordion-inner\"><p><span style=\"font-weight: 400\">ColaReb-Asia <\/span>\u9177\u62c9\u96f7 \u6240\u6709\u8ca9\u552e\u7684\u5546\u54c1\u7686\u5f9e\u7fa9\u5927\u5229\u9032\u53e3\uff0c\u7d14\u624b\u5de5100%\u7fa9\u5927\u5229\u88fd\u9020\u3002<\/p><\/div><\/div><div class=\"accordion-item\">\u00a0<\/div><\/div><\/div><div class=\"accordion-item\">\u00a0<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-2d8a99f\">\n                        <a href=\"#collapse-3e26a886a579213a1855\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-3e26a886a579213a1855\" aria-expanded=\"false\" aria-controls=\"Collapse-3e26a886a579213a1855\">\n                            \n                            <span class=\"ekit-accordion-title\">\u904b\u9001\u6642\u9593\u5927\u7d04\u8981\u591a\u4e45 ?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-3e26a886a579213a1855\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-2d8a99f\" data-parent=\"#accordion-6a579213a1855\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"accordion-item\"><div class=\"accordion-inner\"><div class=\"accordion-item\"><div class=\"accordion-inner\"><p>\u8a02\u55ae\u8655\u7406\u548c\u51fa\u8ca8\u6642\u9593\u70ba\u661f\u671f\u4e00\u81f3\u661f\u671f\u4e94 (\u4e0d\u542b\u5047\u65e5)\u3002\u8acb\u6ce8\u610f\uff0c\u5982\u9047\u5047\u65e5\uff0c\u8a02\u55ae\u7684\u8655\u7406\u53ca\u5bc4\u9001\u6642\u9593\u53ef\u80fd\u6703\u5ef6\u5f8c\u3002<\/p><p>\u6b63\u5e38\u6709\u8ca8\u7684\u60c5\u6cc1\u4e0b\uff0c\u5305\u88f9\u5bc4\u9001\u5929\u6578\u5982\u4e0b:<\/p><ul><li>\u53f0\u7063\u672c\u5cf6: 1-2 \u500b\u5de5\u4f5c\u5929<\/li><li>\u53f0\u7063\u96e2\u5cf6: 1-3 \u500b\u5de5\u4f5c\u5929<\/li><li>\u9999\u6e2f: 3-4 \u500b\u5de5\u4f5c\u5929<\/li><li>\u6fb3\u9580: 4-5 \u500b\u5de5\u4f5c\u5929<\/li><li>\u4e2d\u570b: 3-6 \u500b\u5de5\u4f5c\u5929<\/li><\/ul><p>\u5982\u679c\u9047\u5230\u7f3a\u8ca8\uff0c\u5247\u9700\u89812\u9031\u4ee5\u4e0a\u7684\u6642\u9593\u88dc\u8ca8\u3002<\/p><\/div><\/div><div class=\"accordion-item\">\u00a0<\/div><\/div><\/div><div class=\"accordion-item\">\u00a0<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-2d8a99f\">\n                        <a href=\"#collapse-3f8f29e6a579213a1855\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-3f8f29e6a579213a1855\" aria-expanded=\"false\" aria-controls=\"Collapse-3f8f29e6a579213a1855\">\n                            \n                            <span class=\"ekit-accordion-title\">\u5982\u4f55\u67e5\u8a62\u5546\u54c1\u904b\u9001\u72c0\u6cc1 ?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-3f8f29e6a579213a1855\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-2d8a99f\" data-parent=\"#accordion-6a579213a1855\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"accordion-item\"><div class=\"accordion-inner\"><div class=\"accordion-item\"><div class=\"accordion-inner\"><div class=\"accordion-item\"><div class=\"accordion-inner\"><p>\u60a8\u53ef\u5f9e\u4ee5\u4e0b\u9023\u7d50\u67e5\u8a62:\u00a0<a href=\"https:\/\/www.sf-express.com\/tw\/tc\/dynamic_function\/waybill\/\" target=\"_blank\" rel=\"noopener noreferrer\">SF Express \u904b\u9001\u9032\u5ea6<\/a><\/p><\/div><\/div><div class=\"accordion-item\">\u00a0<\/div><\/div><\/div><\/div><\/div><div class=\"accordion-item\">\u00a0<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-2d8a99f\">\n                        <a href=\"#collapse-e4c4d7c6a579213a1855\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-e4c4d7c6a579213a1855\" aria-expanded=\"false\" aria-controls=\"Collapse-e4c4d7c6a579213a1855\">\n                            \n                            <span class=\"ekit-accordion-title\">\u6211\u6709\u9700\u8981\u66f4\u63db\u9336\u5e36\u5de5\u5177\u662f\u5426\u80fd\u5920\u63a8\u85a6\u7d66\u6211\u5462?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-e4c4d7c6a579213a1855\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-2d8a99f\" data-parent=\"#accordion-6a579213a1855\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"accordion-item\"><div class=\"accordion-inner\"><div class=\"accordion-item\"><div class=\"accordion-inner\"><div class=\"accordion-item\"><div class=\"accordion-inner\"><p>\u82e5\u6709\u9700\u8981\u9336\u8033\u53c9\u5de5\u5177\uff0c\u6b61\u8fce\u8207\u6211\u5011\u806f\u7e6b\u3002<br \/>ColaReb\u9336\u5e36 \u63a8\u85a6\u9577\u671f\u914d\u5408\u7684\u670d\u52d9\u5ee0\u5546\u300a\u745e\u58ebBERGEON\u300b\u5168\u92fc\u96d9\u982d\u9336\u8033\u53c9\u7cfb\u5217\uff0c\u6709\u56db\u6b3e\u898f\u683c\u642d\u914d\u53ef\u9078\uff1a<br \/>\u2022 \u7522\u54c1\u529f\u80fd\uff1a\u53ef\u7576\u9336\u8033\u53c9\u548c\u91dd\u6c96\u4f7f\u7528\uff0c\u76f8\u7576\u5be6\u7528\u7684\u5de5\u5177\u3002<br \/>\u2022 \u4f7f\u7528\u8aaa\u660e\uff1a\u5229\u7528\u9336\u8033\u53c9\u5c16\u7aef\uff0c\u5c07\u9336\u5e36\u9336\u6bbc\u7aef\u5378\u4e0b\u9336\u8033(\u5f48\u7c27\u68d2)\uff0c\u9806\u5229\u5378\u4e0b\u9336\u8033\u5f8c\u66f4\u63db\u9336\u5e36\uff0c\u518d\u4ee5\u6b64\u65b9\u5f0f\u5c07\u9336\u5e36\u6263\u56de\u9336\u6bbc\u7aef\u3002<br \/>\u2022 \u5c6c\u65bc\u5c08\u696d\u7d1a\u5de5\u5177\uff0c\u975e\u5e38\u5bb9\u6613\u4e0a\u624b\uff01<br \/>\u2022 \u4f7f\u7528\u6a5f\u7387\uff1a\u2605\u2605\u2605\u2605\u2605 (\u5c6c\u65bc\u5404\u5927\u77e5\u540d\u54c1\u724c\u5e38\u4f7f\u7528\u5de5\u5177)<\/p><\/div><\/div><div class=\"accordion-item\">\u00a0<\/div><\/div><\/div><\/div><\/div><div class=\"accordion-item\">\u00a0<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Contact us ColaReb Greater China general agent Kaixiang Industrial Co., Ltd.\u2026 <\/p>","protected":false},"author":96,"featured_media":8590,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[374],"tags":[],"class_list":["post-6241","page","type-page","status-publish","has-post-thumbnail","hentry","category-operation"],"_links":{"self":[{"href":"https:\/\/colareb-asia.com\/en\/wp-json\/wp\/v2\/pages\/6241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colareb-asia.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/colareb-asia.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/colareb-asia.com\/en\/wp-json\/wp\/v2\/users\/96"}],"replies":[{"embeddable":true,"href":"https:\/\/colareb-asia.com\/en\/wp-json\/wp\/v2\/comments?post=6241"}],"version-history":[{"count":0,"href":"https:\/\/colareb-asia.com\/en\/wp-json\/wp\/v2\/pages\/6241\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colareb-asia.com\/en\/wp-json\/wp\/v2\/media\/8590"}],"wp:attachment":[{"href":"https:\/\/colareb-asia.com\/en\/wp-json\/wp\/v2\/media?parent=6241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colareb-asia.com\/en\/wp-json\/wp\/v2\/categories?post=6241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colareb-asia.com\/en\/wp-json\/wp\/v2\/tags?post=6241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}